{"id":8235,"date":"2019-05-22T12:16:14","date_gmt":"2019-05-22T12:16:14","guid":{"rendered":"https:\/\/lighthouse-projects.nl\/en\/?page_id=8235"},"modified":"2025-03-14T12:52:06","modified_gmt":"2025-03-14T11:52:06","slug":"contact","status":"publish","type":"page","link":"https:\/\/lighthouse-projects.nl\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_header content_max_width=&#8221;none&#8221; module_class=&#8221;sub_header&#8221; _builder_version=&#8221;4.16&#8243; title_font=&#8221;|on|||&#8221; title_text_color=&#8221;#ffffff&#8221; title_font_size=&#8221;50px&#8221; title_line_height=&#8221;2em&#8221; background_color=&#8221;rgba(255, 255, 255, 0)&#8221; background_image=&#8221;https:\/\/lighthouse-projects.nl\/en\/wp-content\/uploads\/2019\/06\/Lighthouse-Projects-Contact.jpg&#8221; background_position=&#8221;top_center&#8221; min_height=&#8221;480px&#8221; z_index_tablet=&#8221;500&#8243; title_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; title_text_shadow_vertical_length_tablet=&#8221;0px&#8221; title_text_shadow_blur_strength_tablet=&#8221;1px&#8221; content_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; content_text_shadow_vertical_length_tablet=&#8221;0px&#8221; content_text_shadow_blur_strength_tablet=&#8221;1px&#8221; subhead_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; subhead_text_shadow_vertical_length_tablet=&#8221;0px&#8221; subhead_text_shadow_blur_strength_tablet=&#8221;1px&#8221; content_link_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; content_link_text_shadow_vertical_length_tablet=&#8221;0px&#8221; content_link_text_shadow_blur_strength_tablet=&#8221;1px&#8221; content_ul_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; content_ul_text_shadow_vertical_length_tablet=&#8221;0px&#8221; content_ul_text_shadow_blur_strength_tablet=&#8221;1px&#8221; content_ol_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; content_ol_text_shadow_vertical_length_tablet=&#8221;0px&#8221; content_ol_text_shadow_blur_strength_tablet=&#8221;1px&#8221; content_quote_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; content_quote_text_shadow_vertical_length_tablet=&#8221;0px&#8221; content_quote_text_shadow_blur_strength_tablet=&#8221;1px&#8221; button_one_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; button_one_text_shadow_vertical_length_tablet=&#8221;0px&#8221; button_one_text_shadow_blur_strength_tablet=&#8221;1px&#8221; button_two_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; button_two_text_shadow_vertical_length_tablet=&#8221;0px&#8221; button_two_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; box_shadow_horizontal_image_tablet=&#8221;0px&#8221; box_shadow_vertical_image_tablet=&#8221;0px&#8221; box_shadow_blur_image_tablet=&#8221;40px&#8221; box_shadow_spread_image_tablet=&#8221;0px&#8221; box_shadow_horizontal_button_one_tablet=&#8221;0px&#8221; box_shadow_vertical_button_one_tablet=&#8221;0px&#8221; box_shadow_blur_button_one_tablet=&#8221;40px&#8221; box_shadow_spread_button_one_tablet=&#8221;0px&#8221; box_shadow_horizontal_button_two_tablet=&#8221;0px&#8221; box_shadow_vertical_button_two_tablet=&#8221;0px&#8221; box_shadow_blur_button_two_tablet=&#8221;40px&#8221; box_shadow_spread_button_two_tablet=&#8221;0px&#8221; text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_shadow_blur_strength_tablet=&#8221;1px&#8221; global_colors_info=&#8221;{}&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover=&#8221;null&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover=&#8221;null&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover=&#8221;null&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover=&#8221;null&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover=&#8221;null&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover=&#8221;null&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover=&#8221;null&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover=&#8221;null&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover=&#8221;null&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover=&#8221;null&#8221; button_one_letter_spacing__hover_enabled=&#8221;on&#8221; button_one_letter_spacing__hover=&#8221;0&#8243; button_two_letter_spacing__hover_enabled=&#8221;on&#8221; button_two_letter_spacing__hover=&#8221;0&#8243; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover=&#8221;null&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover=&#8221;null&#8221;][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; module_class=&#8221;custom_row contact_page&#8221; _builder_version=&#8221;4.16&#8243; animation_style=&#8221;zoom&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Wij horen graag van u!&#8221; _builder_version=&#8221;4.23&#8243; header_text_color=&#8221;#000000&#8243; z_index_tablet=&#8221;500&#8243; text_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_text_shadow_blur_strength_tablet=&#8221;1px&#8221; link_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; link_text_shadow_vertical_length_tablet=&#8221;0px&#8221; link_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ul_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ul_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ul_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ol_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ol_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ol_text_shadow_blur_strength_tablet=&#8221;1px&#8221; quote_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; quote_text_shadow_vertical_length_tablet=&#8221;0px&#8221; quote_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_2_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_2_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_2_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_3_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_3_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_3_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_4_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_4_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_4_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_5_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_5_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_5_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_6_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_6_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_6_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>\u00a0We look forward to hearing from you<\/h3>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.23&#8243; z_index_tablet=&#8221;500&#8243; text_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_text_shadow_blur_strength_tablet=&#8221;1px&#8221; link_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; link_text_shadow_vertical_length_tablet=&#8221;0px&#8221; link_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ul_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ul_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ul_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ol_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ol_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ol_text_shadow_blur_strength_tablet=&#8221;1px&#8221; quote_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; quote_text_shadow_vertical_length_tablet=&#8221;0px&#8221; quote_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_2_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_2_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_2_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_3_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_3_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_3_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_4_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_4_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_4_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_5_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_5_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_5_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_6_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_6_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_6_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Would you like to know more about what the Lighthouse Projects team can offer you? Please feel free to contact us without obligation. We are happy to help you.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_contact_form email=&#8221;info@lighthouse-projects.nl&#8221; success_message=&#8221; Thank you for your message. We will contact you shortly!&#8221; submit_button_text=&#8221;Send&#8221; _builder_version=&#8221;4.27.4&#8243; _unique_id=&#8221;75f55f7c-4be6-42e9-ab07-5d75433439fb&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#7b8326&#8243; button_bg_color=&#8221;#ffffff&#8221; button_border_color=&#8221;#7b8326&#8243; hover_enabled=&#8221;0&#8243; z_index_tablet=&#8221;500&#8243; border_radii=&#8221;on|1px|1px|1px|1px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#7b8326&#8243; use_border_color=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; captcha=&#8221;off&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_contact_field field_id=&#8221;Name&#8221; field_title=&#8221;Name&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.23&#8243; form_field_font=&#8221;||||&#8221; use_border_color=&#8221;off&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;E-mail&#8221; field_title=&#8221;E-mail address&#8221; field_type=&#8221;email&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.23&#8243; form_field_font=&#8221;||||&#8221; use_border_color=&#8221;off&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Phone_number&#8221; field_title=&#8221;Phone number&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.23&#8243; form_field_font=&#8221;||||&#8221; use_border_color=&#8221;off&#8221; border_style=&#8221;solid&#8221; input_border_radius=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Your_question_or_message&#8221; field_title=&#8221;Your question or message&#8221; field_type=&#8221;text&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.23&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Bedrijfsinformatie&#8221; _builder_version=&#8221;4.23&#8243; z_index_tablet=&#8221;500&#8243; text_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_text_shadow_blur_strength_tablet=&#8221;1px&#8221; link_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; link_text_shadow_vertical_length_tablet=&#8221;0px&#8221; link_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ul_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ul_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ul_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ol_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ol_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ol_text_shadow_blur_strength_tablet=&#8221;1px&#8221; quote_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; quote_text_shadow_vertical_length_tablet=&#8221;0px&#8221; quote_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_2_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_2_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_2_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_3_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_3_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_3_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_4_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_4_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_4_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_5_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_5_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_5_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_6_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_6_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_6_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Company information<\/h3>\n<p>[\/et_pb_text][et_pb_blurb title=&#8221;Address&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe074;||divi||400&#8243; icon_color=&#8221;#7b8326&#8243; icon_placement=&#8221;left&#8221; admin_label=&#8221;Adresblokje&#8221; _builder_version=&#8221;4.23&#8243; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;17&#8243; body_text_color=&#8221;#4b2a00&#8243; background_color=&#8221;#f5f5f5&#8243; max_width_tablet=&#8221;50px&#8221; custom_padding=&#8221;25px|25px|25px|25px&#8221; z_index_tablet=&#8221;500&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Hoeksedijk 69<br \/>3299 AD Maasdam<br \/>The Netherlands<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8221;Company details:&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe078;||divi||400&#8243; icon_color=&#8221;#7b8326&#8243; icon_placement=&#8221;left&#8221; admin_label=&#8221;KvK-BTW-Bank&#8221; _builder_version=&#8221;4.23&#8243; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;17px&#8221; body_text_color=&#8221;#4b2a00&#8243; background_color=&#8221;#f5f5f5&#8243; max_width_tablet=&#8221;50px&#8221; custom_padding=&#8221;25px|25px|25px|25px&#8221; z_index_tablet=&#8221;500&#8243; header_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_text_shadow_blur_strength_tablet=&#8221;1px&#8221; body_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; body_text_shadow_vertical_length_tablet=&#8221;0px&#8221; body_text_shadow_blur_strength_tablet=&#8221;1px&#8221; body_link_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; body_link_text_shadow_vertical_length_tablet=&#8221;0px&#8221; body_link_text_shadow_blur_strength_tablet=&#8221;1px&#8221; body_ul_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; body_ul_text_shadow_vertical_length_tablet=&#8221;0px&#8221; body_ul_text_shadow_blur_strength_tablet=&#8221;1px&#8221; body_ol_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; body_ol_text_shadow_vertical_length_tablet=&#8221;0px&#8221; body_ol_text_shadow_blur_strength_tablet=&#8221;1px&#8221; body_quote_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; body_quote_text_shadow_vertical_length_tablet=&#8221;0px&#8221; body_quote_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; box_shadow_horizontal_image_tablet=&#8221;0px&#8221; box_shadow_vertical_image_tablet=&#8221;0px&#8221; box_shadow_blur_image_tablet=&#8221;40px&#8221; box_shadow_spread_image_tablet=&#8221;0px&#8221; text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_shadow_blur_strength_tablet=&#8221;1px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Kvk\u00a0 75129531<br \/>BTW NL860154592B01<br \/>Bank NL14 RABO0343438100<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8221;E-mail&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe076;||divi||400&#8243; icon_color=&#8221;#7b8326&#8243; icon_placement=&#8221;left&#8221; admin_label=&#8221;E-mail&#8221; _builder_version=&#8221;4.16&#8243; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;17px&#8221; body_text_color=&#8221;#4b2a00&#8243; background_color=&#8221;#f5f5f5&#8243; max_width_tablet=&#8221;50px&#8221; custom_padding=&#8221;25px|25px|25px|25px&#8221; z_index_tablet=&#8221;500&#8243; header_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_text_shadow_blur_strength_tablet=&#8221;1px&#8221; body_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; body_text_shadow_vertical_length_tablet=&#8221;0px&#8221; body_text_shadow_blur_strength_tablet=&#8221;1px&#8221; body_link_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; body_link_text_shadow_vertical_length_tablet=&#8221;0px&#8221; body_link_text_shadow_blur_strength_tablet=&#8221;1px&#8221; body_ul_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; body_ul_text_shadow_vertical_length_tablet=&#8221;0px&#8221; body_ul_text_shadow_blur_strength_tablet=&#8221;1px&#8221; body_ol_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; body_ol_text_shadow_vertical_length_tablet=&#8221;0px&#8221; body_ol_text_shadow_blur_strength_tablet=&#8221;1px&#8221; body_quote_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; body_quote_text_shadow_vertical_length_tablet=&#8221;0px&#8221; body_quote_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; box_shadow_horizontal_image_tablet=&#8221;0px&#8221; box_shadow_vertical_image_tablet=&#8221;0px&#8221; box_shadow_blur_image_tablet=&#8221;40px&#8221; box_shadow_spread_image_tablet=&#8221;0px&#8221; text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_shadow_blur_strength_tablet=&#8221;1px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"mailto:info@lighthouse-projects.nl\" target=\"_blank\" rel=\"noopener noreferrer\">info@lighthouse-projects.nl<\/a><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8221;Phone&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe090;||divi||400&#8243; icon_color=&#8221;#7b8326&#8243; icon_placement=&#8221;left&#8221; admin_label=&#8221;Telefoon&#8221; _builder_version=&#8221;4.16&#8243; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;17&#8243; body_text_color=&#8221;#4b2a00&#8243; background_color=&#8221;#f5f5f5&#8243; max_width_tablet=&#8221;50px&#8221; custom_padding=&#8221;25px|25px|25px|25px&#8221; z_index_tablet=&#8221;500&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Alex +31(0)6 22 88 84 32<br \/>Erik +31(0)6 10 33 57 05<\/p>\n<p>[\/et_pb_blurb][et_pb_social_media_follow follow_button=&#8221;on&#8221; admin_label=&#8221;Social Media Linkedin&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;|||200px&#8221; z_index_tablet=&#8221;500&#8243; button_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; button_text_shadow_vertical_length_tablet=&#8221;0px&#8221; button_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; box_shadow_horizontal_button_tablet=&#8221;0px&#8221; box_shadow_vertical_button_tablet=&#8221;0px&#8221; box_shadow_blur_button_tablet=&#8221;40px&#8221; box_shadow_spread_button_tablet=&#8221;0px&#8221; text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_shadow_blur_strength_tablet=&#8221;1px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;linkedin&#8221; url=&#8221;https:\/\/www.linkedin.com\/company\/lighthouse-projects-bv\/&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#007bb6&#8243; background_color_gradient_direction_tablet=&#8221;180deg&#8221; background_color_gradient_direction_phone=&#8221;180deg&#8221; background_color_gradient_stops_tablet=&#8221;#2b87da 0%|#29c4a9 100%&#8221; background_color_gradient_stops_phone=&#8221;#2b87da 0%|#29c4a9 100%&#8221; background_color_gradient_start_position_tablet=&#8221;0%&#8221; background_color_gradient_start_position_phone=&#8221;0%&#8221; background_color_gradient_end_position_tablet=&#8221;100%&#8221; background_color_gradient_end_position_phone=&#8221;100%&#8221; hover_transition_duration_tablet=&#8221;300ms&#8221; hover_transition_duration_phone=&#8221;300ms&#8221; hover_transition_delay_tablet=&#8221;0ms&#8221; hover_transition_delay_phone=&#8221;0ms&#8221; button_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; button_text_shadow_horizontal_length_phone=&#8221;0px&#8221; button_text_shadow_vertical_length_tablet=&#8221;0px&#8221; button_text_shadow_vertical_length_phone=&#8221;0px&#8221; button_text_shadow_blur_strength_tablet=&#8221;1px&#8221; button_text_shadow_blur_strength_phone=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_horizontal_phone=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_vertical_phone=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_blur_phone=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; box_shadow_spread_phone=&#8221;0px&#8221; box_shadow_horizontal_button_tablet=&#8221;0px&#8221; box_shadow_horizontal_button_phone=&#8221;0px&#8221; box_shadow_vertical_button_tablet=&#8221;0px&#8221; box_shadow_vertical_button_phone=&#8221;0px&#8221; box_shadow_blur_button_tablet=&#8221;40px&#8221; box_shadow_blur_button_phone=&#8221;40px&#8221; box_shadow_spread_button_tablet=&#8221;0px&#8221; box_shadow_spread_button_phone=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;on&#8221; url_new_window=&#8221;on&#8221;]LinkedIn<br \/>\n[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0We look forward to hearing from you &nbsp;Would you like to know more about what the Lighthouse Projects team can offer you? Please feel free to contact us without obligation. We are happy to help you.Company informationHoeksedijk 693299 AD MaasdamThe NetherlandsKvk\u00a0 75129531BTW NL860154592B01Bank NL14 RABO0343438100info@lighthouse-projects.nl Alex +31(0)6 22 88 84 32Erik +31(0)6 10 33 57 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-8235","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lighthouse-projects.nl\/en\/wp-json\/wp\/v2\/pages\/8235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lighthouse-projects.nl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lighthouse-projects.nl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lighthouse-projects.nl\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lighthouse-projects.nl\/en\/wp-json\/wp\/v2\/comments?post=8235"}],"version-history":[{"count":3,"href":"https:\/\/lighthouse-projects.nl\/en\/wp-json\/wp\/v2\/pages\/8235\/revisions"}],"predecessor-version":[{"id":10988,"href":"https:\/\/lighthouse-projects.nl\/en\/wp-json\/wp\/v2\/pages\/8235\/revisions\/10988"}],"wp:attachment":[{"href":"https:\/\/lighthouse-projects.nl\/en\/wp-json\/wp\/v2\/media?parent=8235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}